{"id":13054,"date":"2022-10-19T16:27:28","date_gmt":"2022-10-19T15:27:28","guid":{"rendered":"https:\/\/cgt-bfc.fr\/?p=13054"},"modified":"2022-11-26T08:44:10","modified_gmt":"2022-11-26T07:44:10","slug":"non-monsieur-guerini-les-salaires-ca-nest-pas-en-janvier-cest-tout-de-suite","status":"publish","type":"post","link":"https:\/\/cgt-bfc.fr\/index.php\/2022\/10\/19\/non-monsieur-guerini-les-salaires-ca-nest-pas-en-janvier-cest-tout-de-suite\/","title":{"rendered":"Non, Monsieur Gu\u00e9rini, les salaires, \u00e7a n\u2019est pas en janvier, c\u2019est tout de suite\u00a0!"},"content":{"rendered":"\n<p>Le ministre en charge de la Fonction publique, Stanislas Gu\u00e9rini, a d\u00e9clar\u00e9 hier que \u00ab\u00a0La question des salaires, d\u2019un commun accord avec les organisations syndicales, nous avons d\u00e9cid\u00e9 de l\u2019ouvrir en janvier 2023, apr\u00e8s les \u00e9lections professionnelles\u00a0\u00bb. Il s\u2019agit clairement d\u2019une affirmation mensong\u00e8re.<\/p>\n\n\n\n<p>Pour la CGT, premi\u00e8re organisation syndicale de la Fonction publique, \u00ab\u00a0la question des salaires\u00a0\u00bb pour les fonctionnaires et les agent.es non-titulaires, c\u2019est l\u2019urgence depuis longtemps et l\u2019ouverture de v\u00e9ritables n\u00e9gociations en particulier sur la valeur du point d\u2019indice, c\u2019est imm\u00e9diatement.<\/p>\n\n\n\n<p>La CGT propose dans ces temps difficiles que l\u2019ensemble des \u00e9lus-es et le maire baissent leurs indemnit\u00e9s nettes durant cette p\u00e9riode de crise. Cela montrera aux personnels ainsi qu\u2019aux citoyens-es l\u2019effort r\u00e9el pour pallier \u00e1 cette augmentation exponentielle.<\/p>\n\n\n\n<p>Nos expressions, communiqu\u00e9s, lettres, tracts sont l\u00e0 pour le prouver si besoin.<\/p>\n\n\n\n<p>Comment pourrait-il en \u00eatre autrement pour un syndicat responsable et soucieux de la vie des agentes et des agents, quand les 3,5% consentis sont, d\u2019une part, insuffisants pour couvrir l\u2019inflation de 2022 et, d\u2019autre part, laissent sans r\u00e9ponse les pertes consid\u00e9rables de pouvoir d\u2019achat survenues les ann\u00e9es pass\u00e9es\u00a0?<\/p>\n\n\n\n<p>A la politique aust\u00e9ritaire et lib\u00e9rale du pouvoir ex\u00e9cutif s\u2019ajoutent donc duplicit\u00e9 et double langage.<\/p>\n\n\n\n<p>Ces derniers jours, plusieurs ministres, sous la pression des salari\u00e9.e.s en lutte, ont appel\u00e9 les employeurs du secteur priv\u00e9 \u00e0 augmenter les salaires. Fort bien.<\/p>\n\n\n\n<p>Le probl\u00e8me, c\u2019est que les m\u00eames, lorsqu\u2019ils sont directement employeurs, se refusent \u00e0 garantir le simple maintien du pouvoir d\u2019achat des personnels dont ils ont la charge.<\/p>\n\n\n\n<p>Et que dire de leurs le\u00e7ons en d\u00e9mocratie sociale quand ils stigmatisent le combat des travailleurs des raffineries au pr\u00e9texte de l\u2019accord majoritaire (dans l\u2019entreprise mais pas dans les raffineries) sign\u00e9 entre la direction de Total et deux organisations syndicales&nbsp;?<\/p>\n\n\n\n<p>Dans la Fonction publique, c\u2019est tr\u00e8s majoritairement que plusieurs organisations syndicales estiment que les 3,5% de cet \u00e9t\u00e9 sont tr\u00e8s loin du compte et r\u00e9clament de nouvelles augmentations g\u00e9n\u00e9rales sans d\u00e9lai, d\u00e8s 2022, et pourtant, elles ne sont pas entendues.<\/p>\n\n\n\n<p><strong>Il n\u2019y a donc pas d\u2019ambigu\u00eft\u00e9 possible\u00a0: pour gagner l\u2019indexation des traitements sur l\u2019inflation et des hausses de pouvoir d\u2019achat, pour am\u00e9liorer nos retraites et combattre les nouveaux reculs envisag\u00e9s, pour conqu\u00e9rir l\u2019\u00e9galit\u00e9 salariale et professionnelle, et obtenir tous les moyens n\u00e9cessaires au bon fonctionnement des services publics, il faut encore \u00e9lever le rapport de forces et l\u2019inscrire dans la dur\u00e9e.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Le ministre en charge de la Fonction publique, Stanislas Gu\u00e9rini, a d\u00e9clar\u00e9 hier que \u00ab\u00a0La question des salaires, d\u2019un commun accord avec les organisations syndicales, <a class=\"mh-excerpt-more\" href=\"https:\/\/cgt-bfc.fr\/index.php\/2022\/10\/19\/non-monsieur-guerini-les-salaires-ca-nest-pas-en-janvier-cest-tout-de-suite\/\" title=\"Non, Monsieur Gu\u00e9rini, les salaires, \u00e7a n\u2019est pas en janvier, c\u2019est tout de suite\u00a0!\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":13069,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1,31,30],"tags":[],"class_list":["post-13054","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actu","category-cgt","category-luttes-cgt"],"jetpack_featured_media_url":"https:\/\/cgt-bfc.fr\/wp-content\/uploads\/2022\/10\/guerini_s____-1.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cgt-bfc.fr\/index.php\/wp-json\/wp\/v2\/posts\/13054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cgt-bfc.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cgt-bfc.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cgt-bfc.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cgt-bfc.fr\/index.php\/wp-json\/wp\/v2\/comments?post=13054"}],"version-history":[{"count":11,"href":"https:\/\/cgt-bfc.fr\/index.php\/wp-json\/wp\/v2\/posts\/13054\/revisions"}],"predecessor-version":[{"id":13071,"href":"https:\/\/cgt-bfc.fr\/index.php\/wp-json\/wp\/v2\/posts\/13054\/revisions\/13071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cgt-bfc.fr\/index.php\/wp-json\/wp\/v2\/media\/13069"}],"wp:attachment":[{"href":"https:\/\/cgt-bfc.fr\/index.php\/wp-json\/wp\/v2\/media?parent=13054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cgt-bfc.fr\/index.php\/wp-json\/wp\/v2\/categories?post=13054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cgt-bfc.fr\/index.php\/wp-json\/wp\/v2\/tags?post=13054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}