{"id":15412,"date":"2024-01-30T15:35:37","date_gmt":"2024-01-30T14:35:37","guid":{"rendered":"https:\/\/cgt-bfc.fr\/?p=15412"},"modified":"2024-02-02T08:33:07","modified_gmt":"2024-02-02T07:33:07","slug":"webinaire-du-cnfpt-sur-les-40-ans-de-la-loi-instituant-la-fonction-publique-territoriale","status":"publish","type":"post","link":"https:\/\/cgt-bfc.fr\/index.php\/2024\/01\/30\/webinaire-du-cnfpt-sur-les-40-ans-de-la-loi-instituant-la-fonction-publique-territoriale\/","title":{"rendered":"webinaire du CNFPT sur les 40 ans de la loi instituant la Fonction Publique Territoriale"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le 26 janvier 1984 \u00e9tait publi\u00e9e la loi n\u00b084-53 portant dispositions statutaires relatives \u00e0 la fonction publique territoriale. La cr\u00e9ation de ce statut a marqu\u00e9 la reconnaissance, il y a 40 ans, de la place et du r\u00f4le particulier des agents publics dans la soci\u00e9t\u00e9 \u00e0 la fois responsable vis-\u00e0-vis d\u2019elle et \u00e0 son service.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce 40\u00e8me anniversaire de la loi du 26 janvier 1984 doit \u00eatre l\u2019occasion de faire \u00e0 la fois le bilan du chemin parcouru, et de s\u2019interroger sur les \u00e9volutions qu\u2019il conviendrait d\u2019op\u00e9rer au statut de la fonction publique territoriale au moment o\u00f9 le Gouvernement annonce, pour le d\u00e9but de l\u2019ann\u00e9e 2024, la pr\u00e9sentation d\u2019un projet de loi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ainsi, \u00e0 l\u2019occasion de ce colloque, 4 th\u00e8mes seront abord\u00e9s&nbsp;:<br>\u00b7 le dialogue social<br>\u00b7 l\u2019entr\u00e9e en fonction<br>\u00b7 le parcours professionnel<br>\u00b7 la r\u00e9mun\u00e9ration<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ils donneront lieu, chacun, \u00e0 une table ronde \u00e0 laquelle participeront des repr\u00e9sentants de la coordination des employeurs territoriaux et des repr\u00e9sentants des organisations syndicales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/vimeo.com\/903239254\/0d8e14f5fe?ts=0&amp;share=copy\">La vid\u00e9o :ICI<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sur le site du CNFPT les diff\u00e9rents t\u00e9moignages<a href=\"https:\/\/www.cnfpt.fr\/se-former\/se-former-autrement\/participer-a-nos-evenements\/loi-du-26-janvier-1984-40-ans\/national\">. ICI<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Le 26 janvier 1984 \u00e9tait publi\u00e9e la loi n\u00b084-53 portant dispositions statutaires relatives \u00e0 la fonction publique territoriale. La cr\u00e9ation de ce statut a marqu\u00e9 <a class=\"mh-excerpt-more\" href=\"https:\/\/cgt-bfc.fr\/index.php\/2024\/01\/30\/webinaire-du-cnfpt-sur-les-40-ans-de-la-loi-instituant-la-fonction-publique-territoriale\/\" title=\"webinaire du CNFPT sur les 40 ans de la loi instituant la Fonction Publique Territoriale\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":15416,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-15412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actu"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/cgt-bfc.fr\/wp-content\/uploads\/2024\/01\/40_ans.png","_links":{"self":[{"href":"https:\/\/cgt-bfc.fr\/index.php\/wp-json\/wp\/v2\/posts\/15412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cgt-bfc.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cgt-bfc.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cgt-bfc.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cgt-bfc.fr\/index.php\/wp-json\/wp\/v2\/comments?post=15412"}],"version-history":[{"count":5,"href":"https:\/\/cgt-bfc.fr\/index.php\/wp-json\/wp\/v2\/posts\/15412\/revisions"}],"predecessor-version":[{"id":15418,"href":"https:\/\/cgt-bfc.fr\/index.php\/wp-json\/wp\/v2\/posts\/15412\/revisions\/15418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cgt-bfc.fr\/index.php\/wp-json\/wp\/v2\/media\/15416"}],"wp:attachment":[{"href":"https:\/\/cgt-bfc.fr\/index.php\/wp-json\/wp\/v2\/media?parent=15412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cgt-bfc.fr\/index.php\/wp-json\/wp\/v2\/categories?post=15412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cgt-bfc.fr\/index.php\/wp-json\/wp\/v2\/tags?post=15412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}